{"id":8930,"date":"2024-10-31T22:17:45","date_gmt":"2024-10-31T22:17:45","guid":{"rendered":"https:\/\/tcmigration.com\/refus-des-conjoints-de-diplomates\/"},"modified":"2024-11-06T05:18:14","modified_gmt":"2024-11-06T05:18:14","slug":"refus-des-conjoints-de-diplomates","status":"publish","type":"post","link":"https:\/\/tcmigration.com\/fr\/refus-des-conjoints-de-diplomates\/","title":{"rendered":"Refus des conjoints de diplomates"},"content":{"rendered":"<p>Finalement, la justice a pr\u00e9valu.<\/p>\n<h2>Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) a r\u00e9cemment annul\u00e9 le refus d&rsquo;une demande au titre de la cat\u00e9gorie de l&rsquo;exp\u00e9rience canadienne pr\u00e9sent\u00e9e par le conjoint d&rsquo;un diplomate accr\u00e9dit\u00e9 au Canada.<\/h2>\n<p>Le refus de l&rsquo;IRCC \u00e9tait bas\u00e9 sur la pr\u00e9misse qu&rsquo;avant l&rsquo;entr\u00e9e du demandeur, il n&rsquo;avait pas demand\u00e9 de visa de r\u00e9sident temporaire. L&rsquo;agent n&rsquo;a pas consid\u00e9r\u00e9 que le R\u00e8glement sur l&rsquo;immigration dispensait les repr\u00e9sentants \u00e9trangers, et d&rsquo;autres personnes, de l&rsquo;obligation de demander un visa de r\u00e9sident temporaire avant l&rsquo;entr\u00e9e. L&rsquo;agent a \u00e9galement conclu que le conjoint accr\u00e9dit\u00e9 n&rsquo;\u00e9tait pas un r\u00e9sident temporaire du Canada pendant sa p\u00e9riode d&#8217;emploi. Par cons\u00e9quent, IRCC a d\u00e9termin\u00e9 que le travail n&rsquo;\u00e9tait pas consid\u00e9r\u00e9 comme une exp\u00e9rience professionnelle \u00ab\u00a0canadienne\u00a0\u00bb. \u00c0 la suite de notre \u00e9valuation d\u00e9taill\u00e9e de ce cas, nous avons conclu que l&rsquo;agent d&rsquo;IRCC avait commis plusieurs erreurs. Il a mal compris les lois et accords internationaux pertinents, ainsi que l&rsquo;accord du pays d&rsquo;accueil sign\u00e9 par le Canada avec l&rsquo;\u00c9tat \u00e9tranger, qui comprenait des d\u00e9tails sur les conditions d&rsquo;obtention d&rsquo;un num\u00e9ro d&rsquo;assurance sociale pour les membres de la famille accr\u00e9dit\u00e9s, y compris les r\u00e8gles relatives \u00e0 l&rsquo;exercice d&rsquo;un emploi r\u00e9mun\u00e9r\u00e9. Nous avons pr\u00e9sent\u00e9 \u00e0 IRCC une demande de r\u00e9examen de la d\u00e9cision de rejet de ce dossier. Dans nos observations, nous avons plaid\u00e9 en faveur d&rsquo;une interpr\u00e9tation appropri\u00e9e des lois pertinentes. Notre demande de r\u00e9examen a \u00e9t\u00e9 accept\u00e9e. L&rsquo;IRCC a retir\u00e9 son refus et a finalement approuv\u00e9 la demande. L&rsquo;IRCC a accept\u00e9 notre position sans poser de questions. La r\u00e9ponse \u00e9crite au demandeur commen\u00e7ait ainsi \u00ab\u00a0Votre demande de r\u00e9sidence permanente a \u00e9t\u00e9 approuv\u00e9e. La derni\u00e8re \u00e9tape du traitement de votre demande consiste \u00e0 confirmer votre r\u00e9sidence permanente et \u00e0 cr\u00e9er votre carte de r\u00e9sident permanent. Vous effectuerez ce processus par l&rsquo;entremise du Portail des r\u00e9sidents permanents (Confirmation RP). Dans le portail, vous confirmerez que vous et les personnes \u00e0 votre charge \u00eates au Canada, vous fournirez votre adresse canadienne et vous soumettrez votre photo pour cr\u00e9er votre carte de r\u00e9sident permanent\u00a0\u00bb. Nous maintenons qu&rsquo;il existe un malentendu \u00e9vident au sein du d\u00e9partement IRCC en ce qui concerne la cat\u00e9gorie de l&rsquo;exp\u00e9rience canadienne et l&rsquo;\u00e9ligibilit\u00e9 et la qualification des repr\u00e9sentants \u00e9trangers accr\u00e9dit\u00e9s et de leurs familles. Le point essentiel est que les agents croient \u00e0 tort que les ambassades et les consulats sont des territoires souverains \u00e9trangers. Rien n&rsquo;est plus faux. Il s&rsquo;agit d&rsquo;une repr\u00e9sentation erron\u00e9e que l&rsquo;on retrouve dans les films. Le malaise que m&rsquo;inspirent les d\u00e9cisions d&rsquo;IRCC tient au fait qu&rsquo;elles sont examin\u00e9es superficiellement et simplement comme une question territoriale et qu&rsquo;elles pr\u00e9supposent \u00e0 tort que les ambassades et les consulats sont de petits \u00c9tats \u00e9trangers autonomes \u00e0 l&rsquo;int\u00e9rieur du Canada qui ont toute autorit\u00e9 sur l&rsquo;espace lou\u00e9 ou achet\u00e9 sur le territoire canadien. Bien qu&rsquo;ils repr\u00e9sentent des \u00c9tats \u00e9trangers b\u00e9n\u00e9ficiant de certaines immunit\u00e9s, le Canada ne leur accorde pas un pouvoir absolu et illimit\u00e9. Les locaux demeurent le sol souverain de l&rsquo;\u00c9tat d&rsquo;accueil &#8211; le Canada. Ces locaux sont inviolables, mais ils ne sont jamais le sol souverain du pays d&rsquo;envoi. Oui, la loi canadienne est supr\u00eame, mais je crains que les agents ne prennent des d\u00e9cisions fond\u00e9es sur des conclusions erron\u00e9es et sur une mauvaise compr\u00e9hension de l&rsquo;ordre l\u00e9gitime convenu entre le Canada et le pays d&rsquo;accueil. Ces accords sont bas\u00e9s, en partie, sur la Convention de Vienne de 1961 sur les relations diplomatiques et sur la Convention de Gen\u00e8ve de 1963 sur les relations consulaires.   <\/p>\n<p>Si votre demande a \u00e9t\u00e9 refus\u00e9e parce que l&rsquo;exp\u00e9rience professionnelle qualifi\u00e9e canadienne que vous avez acquise en tant que titulaire d&rsquo;une accr\u00e9ditation diplomatique a \u00e9t\u00e9 consid\u00e9r\u00e9e comme ayant \u00e9t\u00e9 acquise sans statut de r\u00e9sident temporaire au Canada, vous devez contester cette d\u00e9cision.<\/p>\n<h3>A propos de cette affaire<\/h3>\n<blockquote><p>Je suis le conjoint d&rsquo;un diplomate, je travaille au Canada depuis 2 ans en tant que professionnel de l&rsquo;informatique avec un doctorat et je paie des imp\u00f4ts comme n&rsquo;importe quel autre Canadien. N\u00e9anmoins, IRCC a refus\u00e9 ma demande de r\u00e9sidence permanente au Canada sous pr\u00e9texte que je ne pouvais pas demander la r\u00e9sidence permanente au Canada en premier lieu puisque je n&rsquo;\u00e9tais pas un r\u00e9sident temporaire en raison de mon accr\u00e9ditation. Elda m&rsquo;a aid\u00e9 \u00e0 contester cette affirmation en fournissant des arguments prouvant que le statut diplomatique est une condition de la cat\u00e9gorie des r\u00e9sidents temporaires. Lorsque nous avons demand\u00e9 un r\u00e9examen, l&rsquo;IRCC n&rsquo;a pas eu d&rsquo;autre choix que d&rsquo;admettre son erreur et de m&rsquo;accorder le statut de r\u00e9sident permanent.<br \/>\nElda a \u00e9t\u00e9 mon avocate optimiste qui ne s&rsquo;est pas rendue parce qu&rsquo;elle \u00e9tait convaincue que l&rsquo;agent responsable de la d\u00e9cision avait commis des injustices et des erreurs lors du rejet de ma demande. Elda ne s&rsquo;est pas content\u00e9e de monter un dossier juridique \u00e0 partir de ma situation, elle m&rsquo;a \u00e9galement aid\u00e9e \u00e0 le transmettre \u00e0 IRCC et \u00e0 frapper aux portes du d\u00e9partement dans des moments difficiles o\u00f9 personne n&rsquo;\u00e9tait dispos\u00e9 \u00e0 les ouvrir ou \u00e0 \u00e9couter mon dossier. C&rsquo;est une vraie professionnelle et elle est extr\u00eamement d\u00e9vou\u00e9e \u00e0 ses clients. Elle n&rsquo;a jamais abandonn\u00e9, m\u00eame lorsque je perdais espoir. La demande de r\u00e9examen de mon dossier refus\u00e9 dans le cadre d&rsquo;Entr\u00e9e express a \u00e9t\u00e9 accept\u00e9e contre toute attente par IRCC, sans aucune contestation. C&rsquo;est en grande partie gr\u00e2ce aux efforts d&rsquo;Elda que notre confiance dans le syst\u00e8me d&rsquo;immigration canadien a \u00e9t\u00e9 r\u00e9tablie. <\/p>\n<p><em>De A.B. Moshe<\/em><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Finalement, la justice a pr\u00e9valu. Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC) a r\u00e9cemment annul\u00e9 le refus d&rsquo;une demande au titre de la cat\u00e9gorie de l&rsquo;exp\u00e9rience canadienne pr\u00e9sent\u00e9e par le conjoint d&rsquo;un diplomate accr\u00e9dit\u00e9 au Canada. Le refus de l&rsquo;IRCC \u00e9tait bas\u00e9 sur la pr\u00e9misse qu&rsquo;avant l&rsquo;entr\u00e9e du demandeur, il n&rsquo;avait pas demand\u00e9 de visa de[&#8230;]\n","protected":false},"author":2,"featured_media":8931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[50,49],"tags":[],"class_list":["post-8930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomates-et-representants-etrangers","category-immigration-canadienne"],"_links":{"self":[{"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/posts\/8930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/comments?post=8930"}],"version-history":[{"count":0,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/posts\/8930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/media\/8931"}],"wp:attachment":[{"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/media?parent=8930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/categories?post=8930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tcmigration.com\/fr\/wp-json\/wp\/v2\/tags?post=8930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}